{"id":719,"date":"2018-07-04T10:52:05","date_gmt":"2018-07-04T13:52:05","guid":{"rendered":"https:\/\/blue-kingfisher-291148.hostingersite.com\/?page_id=719"},"modified":"2023-08-18T16:51:31","modified_gmt":"2023-08-18T19:51:31","slug":"editora","status":"publish","type":"page","link":"https:\/\/csem.org.br\/pt_br\/editora\/","title":{"rendered":"Editora"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"719\" class=\"elementor elementor-719\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74a79b3 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"74a79b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9977c5\" data-id=\"e9977c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f622f8 elementor-widget elementor-widget-template\" data-id=\"5f622f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"19749\" class=\"elementor elementor-19749\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15b34725 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15b34725\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3622abe\" data-id=\"3622abe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-17cf0bf5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17cf0bf5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-295ae005\" data-id=\"295ae005\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec1d722 elementor-widget elementor-widget-pp-breadcrumbs\" data-id=\"ec1d722\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;breadcrumbs_type&quot;:&quot;powerpack&quot;}\" data-widget_type=\"pp-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"pp-breadcrumbs pp-breadcrumbs-powerpack\">\t\t<li class=\"pp-breadcrumbs-item pp-breadcrumbs-item-home\">\n\t\t\t<a class=\"pp-breadcrumbs-crumb pp-breadcrumbs-crumb-link pp-breadcrumbs-crumb-home\" href=\"https:\/\/csem.org.br\/pt_br\" title=\"In\u00edcio \">\n\t\t\t\t<span class=\"pp-breadcrumbs-text\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-folder-open\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\tIn\u00edcio \t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t<li class=\"pp-breadcrumbs-separator\">\t\t\t\t<span class='pp-separator-icon pp-icon'>\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t<\/li><\/ul>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-17b588ad elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"17b588ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12039253 elementor-share-buttons--view-icon elementor-share-buttons--skin-flat elementor-share-buttons--shape-circle elementor-grid-3 elementor-hidden-tablet elementor-hidden-mobile elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"12039253\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_whatsapp\" role=\"button\" tabindex=\"0\" aria-label=\"Compartilhar no whatsapp\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-whatsapp\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_email\" role=\"button\" tabindex=\"0\" aria-label=\"Compartilhar no email\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_print\" role=\"button\" tabindex=\"0\" aria-label=\"Compartilhar no print\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fas fa-print\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f1466b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f1466b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78f4c2c6\" data-id=\"78f4c2c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0af2cef elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0af2cef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0d2b893\" data-id=\"0d2b893\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bbc2f3 elementor-widget elementor-widget-global elementor-global-21035 elementor-widget-pp-advanced-menu\" data-id=\"9bbc2f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;menu_type&quot;:&quot;off-canvas&quot;,&quot;onepage_menu&quot;:&quot;yes&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;show_submenu_on&quot;:&quot;hover&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;fas fa-caret-down&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;icon&quot;,&quot;toggle_icon_type&quot;:&quot;hamburger&quot;,&quot;show_responsive_submenu_on&quot;:&quot;icon&quot;}\" data-widget_type=\"pp-advanced-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t<div class=\"pp-advanced-menu-main-wrapper pp-advanced-menu__align-center pp-advanced-menu--dropdown-tablet pp-advanced-menu--type-off-canvas pp-advanced-menu__text-align- pp-advanced-menu--toggle pp-advanced-menu--icon\">\n\t\t\t\t\t\t\t\t<nav id=\"pp-menu-9bbc2f3\" class=\"pp-advanced-menu--main pp-advanced-menu__container pp-advanced-menu--layout-horizontal pp--pointer-background e--animation-fade\" aria-label=\"Quem Somos\" data-settings=\"{&quot;menu_id&quot;:&quot;9bbc2f3&quot;,&quot;breakpoint&quot;:&quot;tablet&quot;,&quot;full_width&quot;:false}\"><ul id=\"menu-quem-somos\" class=\"pp-advanced-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21029\"><a href=\"https:\/\/csem.org.br\/pt_br\/institucional\/\" class=\"pp-menu-item\">Institucional<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21028\"><a href=\"https:\/\/csem.org.br\/pt_br\/equipe\/\" class=\"pp-menu-item\">Equipe<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21027\"><a href=\"https:\/\/csem.org.br\/pt_br\/editora\/\" class=\"pp-menu-item\">Editora<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21030\"><a href=\"https:\/\/csem.org.br\/pt_br\/relatorios-anuais\/\" class=\"pp-menu-item\">Relat\u00f3rios Anuais<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21031\"><a href=\"https:\/\/csem.org.br\/pt_br\/parceiros\/\" class=\"pp-menu-item\">Parceiros<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21026\"><a href=\"https:\/\/csem.org.br\/pt_br\/congregacao\/\" class=\"pp-menu-item\">Congrega\u00e7\u00e3o<\/a><\/li>\n<\/ul><\/nav>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-menu-toggle pp-menu-toggle-on-tablet\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-hamburger\">\n\t\t\t\t\t\t\t<div class=\"pp-hamburger-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-hamburger-inner\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<nav class=\"pp-advanced-menu--dropdown pp-menu-style-toggle pp-advanced-menu__container pp-menu-9bbc2f3 pp-menu-off-canvas pp-menu-off-canvas-left\" data-settings=\"{&quot;menu_id&quot;:&quot;9bbc2f3&quot;,&quot;breakpoint&quot;:&quot;tablet&quot;,&quot;full_width&quot;:false}\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-menu-close-wrap\">\n\t\t\t\t\t\t<div class=\"pp-menu-close\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<ul id=\"menu-quem-somos-1\" class=\"pp-advanced-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21029\"><a href=\"https:\/\/csem.org.br\/pt_br\/institucional\/\" class=\"pp-menu-item\">Institucional<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21028\"><a href=\"https:\/\/csem.org.br\/pt_br\/equipe\/\" class=\"pp-menu-item\">Equipe<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21027\"><a href=\"https:\/\/csem.org.br\/pt_br\/editora\/\" class=\"pp-menu-item\">Editora<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21030\"><a href=\"https:\/\/csem.org.br\/pt_br\/relatorios-anuais\/\" class=\"pp-menu-item\">Relat\u00f3rios Anuais<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21031\"><a href=\"https:\/\/csem.org.br\/pt_br\/parceiros\/\" class=\"pp-menu-item\">Parceiros<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21026\"><a href=\"https:\/\/csem.org.br\/pt_br\/congregacao\/\" class=\"pp-menu-item\">Congrega\u00e7\u00e3o<\/a><\/li>\n<\/ul>\t\t\t\t\t\t\t<\/nav>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9e82472 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e82472\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky_offset_mobile&quot;:5,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f2cfe2a\" data-id=\"f2cfe2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb3bf54 elementor-widget elementor-widget-heading\" data-id=\"cb3bf54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Menu r\u00e1pido<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5ffb36c\" data-id=\"5ffb36c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-345a094 elementor-widget elementor-widget-global elementor-global-21035 elementor-widget-pp-advanced-menu\" data-id=\"345a094\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;menu_type&quot;:&quot;off-canvas&quot;,&quot;onepage_menu&quot;:&quot;yes&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;show_submenu_on&quot;:&quot;hover&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;fas fa-caret-down&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;icon&quot;,&quot;toggle_icon_type&quot;:&quot;hamburger&quot;,&quot;show_responsive_submenu_on&quot;:&quot;icon&quot;}\" data-widget_type=\"pp-advanced-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t<div class=\"pp-advanced-menu-main-wrapper pp-advanced-menu__align-center pp-advanced-menu--dropdown-tablet pp-advanced-menu--type-off-canvas pp-advanced-menu__text-align- pp-advanced-menu--toggle pp-advanced-menu--icon\">\n\t\t\t\t\t\t\t\t<nav id=\"pp-menu-345a094\" class=\"pp-advanced-menu--main pp-advanced-menu__container pp-advanced-menu--layout-horizontal pp--pointer-background e--animation-fade\" aria-label=\"Quem Somos\" data-settings=\"{&quot;menu_id&quot;:&quot;345a094&quot;,&quot;breakpoint&quot;:&quot;tablet&quot;,&quot;full_width&quot;:false}\"><ul id=\"menu-quem-somos-2\" class=\"pp-advanced-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21029\"><a href=\"https:\/\/csem.org.br\/pt_br\/institucional\/\" class=\"pp-menu-item\">Institucional<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21028\"><a href=\"https:\/\/csem.org.br\/pt_br\/equipe\/\" class=\"pp-menu-item\">Equipe<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21027\"><a href=\"https:\/\/csem.org.br\/pt_br\/editora\/\" class=\"pp-menu-item\">Editora<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21030\"><a href=\"https:\/\/csem.org.br\/pt_br\/relatorios-anuais\/\" class=\"pp-menu-item\">Relat\u00f3rios Anuais<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21031\"><a href=\"https:\/\/csem.org.br\/pt_br\/parceiros\/\" class=\"pp-menu-item\">Parceiros<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21026\"><a href=\"https:\/\/csem.org.br\/pt_br\/congregacao\/\" class=\"pp-menu-item\">Congrega\u00e7\u00e3o<\/a><\/li>\n<\/ul><\/nav>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-menu-toggle pp-menu-toggle-on-tablet\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-hamburger\">\n\t\t\t\t\t\t\t<div class=\"pp-hamburger-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-hamburger-inner\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<nav class=\"pp-advanced-menu--dropdown pp-menu-style-toggle pp-advanced-menu__container pp-menu-345a094 pp-menu-off-canvas pp-menu-off-canvas-left\" data-settings=\"{&quot;menu_id&quot;:&quot;345a094&quot;,&quot;breakpoint&quot;:&quot;tablet&quot;,&quot;full_width&quot;:false}\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-menu-close-wrap\">\n\t\t\t\t\t\t<div class=\"pp-menu-close\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<ul id=\"menu-quem-somos-3\" class=\"pp-advanced-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21029\"><a href=\"https:\/\/csem.org.br\/pt_br\/institucional\/\" class=\"pp-menu-item\">Institucional<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21028\"><a href=\"https:\/\/csem.org.br\/pt_br\/equipe\/\" class=\"pp-menu-item\">Equipe<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21027\"><a href=\"https:\/\/csem.org.br\/pt_br\/editora\/\" class=\"pp-menu-item\">Editora<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21030\"><a href=\"https:\/\/csem.org.br\/pt_br\/relatorios-anuais\/\" class=\"pp-menu-item\">Relat\u00f3rios Anuais<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21031\"><a href=\"https:\/\/csem.org.br\/pt_br\/parceiros\/\" class=\"pp-menu-item\">Parceiros<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21026\"><a href=\"https:\/\/csem.org.br\/pt_br\/congregacao\/\" class=\"pp-menu-item\">Congrega\u00e7\u00e3o<\/a><\/li>\n<\/ul>\t\t\t\t\t\t\t<\/nav>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-57aa871 elementor-widget elementor-widget-heading\" data-id=\"57aa871\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">EDITORA<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53df92b4 elementor-widget elementor-widget-text-editor\" data-id=\"53df92b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A Editora CSEM atua em dois eixos: a produ\u00e7\u00e3o e edi\u00e7\u00e3o da Revista Interdisciplinar da Mobilidade Humana \u2013 REMHU e a publica\u00e7\u00e3o de livros pr\u00f3prios ou em parceria com organiza\u00e7\u00f5es afins. Todas as atividades da Editora CSEM est\u00e3o relacionadas com o cumprimento da Miss\u00e3o do CSEM de fomentar, produzir e disseminar conhecimentos cient\u00edficos e interdisciplinares sobre as migra\u00e7\u00f5es e os deslocamentos for\u00e7ados e processos afins, na perspectiva dos direitos humanos.<\/p><p>A Editora CSEM publica em diferentes idiomas e visa alcan\u00e7ar diferentes p\u00fablicos, especialmente migrantes\/refugiados e profissionais que atuam e estudam temas relacionados com a mobilidade humana.<\/p><p>A maioria dos textos s\u00e3o produzidos em formato Ebook em pdf e, tamb\u00e9m, s\u00e3o impressos. Livros em formato digital s\u00e3o de acesso gratuito e livros impressos s\u00e3o vendidos e podem ser solicitados pelo email\u00a0<a href=\"mailto:csem@csem.org.br\">csem@csem.org.br<\/a>.<\/p><p>As S\u00e9ries de livros da Editora CSEM s\u00e3o:<\/p><p><strong>A S\u00e9rie Migra\u00e7\u00f5es<\/strong>\u00a0publica textos interdisciplinares sobre temas relacionados com a mobilidade humana. Entre os volumes da S\u00e9rie Migra\u00e7\u00f5es a Editora j\u00e1 publicou estudos de colaboradores do CSEM, colet\u00e2neas de estudos organizados pelo CSEM, assim como textos produzidos em eventos organizados pelo CSEM ou em parcerias afins.<\/p><p><strong>A S\u00e9rie Caminhos<\/strong>\u00a0publica estudos autorais e colet\u00e2neas relacionados com teologia pastoral e mobilidade humana, assim como atos de eventos relativos a tem\u00e1ticas pastorais com foco nas migra\u00e7\u00f5es e no ref\u00fagio.<\/p><p><strong>A S\u00e9rie Mem\u00f3rias<\/strong>\u00a0publica estudos e narrativas de abordagem hist\u00f3rica, sobretudo com foco na atua\u00e7\u00e3o das Irm\u00e3s Mission\u00e1rias Scalabrinianas. Nesta S\u00e9rie encontram-se os volumes da Hist\u00f3ria da Congrega\u00e7\u00e3o, escritos pela historiadora Lice Maria Signor.<\/p><p><strong>A S\u00e9rie Ecumene<\/strong>\u00a0visa responder a uma car\u00eancia de publica\u00e7\u00f5es de teologia da mobilidade humana voltada, prioritariamente, para lideran\u00e7as religiosas\/eclesiais que atuam nos \u00e2mbitos acad\u00eamico, institucional ou pastoral.<\/p><p>Desenvolvida em parceria com a CLAR \u2013 Confedera\u00e7\u00e3o Latino-Americana de Religiosos, a S\u00e9rie Ecumene \u00e9 um projeto plurianual de produ\u00e7\u00e3o e publica\u00e7\u00e3o de estudos de teologia da mobilidade humana, com vistas a promover a reflex\u00e3o e a atua\u00e7\u00e3o no \u00e2mbito migrat\u00f3rio e do ref\u00fagio. O projeto editorial \u2013 S\u00e9rie Ecumene \u2013 produz, em portugu\u00eas e em espanhol, colet\u00e2neas tem\u00e1ticas relacionados com a mobilidade humana, que s\u00e3o disponibilizados, inclusive, em vers\u00e3o digital para download gratuito.<\/p><p><strong>A S\u00e9rie Caminando con los Migrantes<\/strong>\u00a0produz e divulga publica\u00e7\u00f5es coordenadas e desenvolvidas em conjunto com a Comiss\u00e3o da Miss\u00e3o Apost\u00f3lica das Prov\u00edncias da Congrega\u00e7\u00e3o das Irm\u00e3s Mission\u00e1rias Scalabrinianas. Tem o objetivo de fortalecer e dar visibilidade \u00e0s miss\u00f5es scalabrinianas MSCS de l\u00edngua espanhola. Os volumes publicados nesta S\u00e9rie s\u00e3o uma oportunidade de sistematizar boas pr\u00e1ticas, contribuir com a literatura local, documentar as a\u00e7\u00f5es das Irm\u00e3s MSCS e colaboradores\/as da miss\u00e3o. Dados coletados e produzidos pelo Sistema Paroikos contribuem com insumos para esta S\u00e9rie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1626abf elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"1626abf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A Editora CSEM atua em dois eixos: a produ\u00e7\u00e3o e edi\u00e7\u00e3o da Revista Interdisciplinar da Mobilidade Humana \u2013 REMHU e a publica\u00e7\u00e3o de livros pr\u00f3prios ou em parceria com organiza\u00e7\u00f5es afins. Todas as atividades da Editora CSEM est\u00e3o relacionadas com o cumprimento da Miss\u00e3o do CSEM de fomentar, produzir e disseminar conhecimentos cient\u00edficos e interdisciplinares sobre as migra\u00e7\u00f5es e os deslocamentos for\u00e7ados e processos afins, na perspectiva dos direitos humanos.<\/p><p>A Editora CSEM publica em diferentes idiomas e visa alcan\u00e7ar diferentes p\u00fablicos, especialmente migrantes\/refugiados e profissionais que atuam e estudam temas relacionados com a mobilidade humana.<\/p><p>A maioria dos textos s\u00e3o produzidos em formato Ebook em pdf e, tamb\u00e9m, s\u00e3o impressos. Livros em formato digital s\u00e3o de acesso gratuito e livros impressos s\u00e3o vendidos e podem ser solicitados pelo email\u00a0<a href=\"mailto:csem@csem.org.br\">csem@csem.org.br<\/a>.<\/p><p>As S\u00e9ries de livros da Editora CSEM s\u00e3o:<\/p><p>A <strong>S\u00e9rie Migra\u00e7\u00f5es<\/strong> publica textos interdisciplinares sobre temas relacionados com a mobilidade humana. Entre os 21 volumes da S\u00e9rie Migra\u00e7\u00f5es a Editora j\u00e1 publicou estudos de colaboradores do CSEM, colet\u00e2neas de estudos organizados pelo CSEM e tamb\u00e9m textos produzidos em eventos organizados pelo CSEM ou em parcerias afins.<\/p><p>A <strong>S\u00e9rie Caminhos<\/strong> publica estudos autorais e colet\u00e2neas de teologia da mobilidade humana e atos de eventos relativos a tem\u00e1ticas pastorais com foco nas migra\u00e7\u00f5es e no ref\u00fagio. O \u00faltimo livro da S\u00e9rie Caminhos, publicado no ano de 2018, \u00e9 \u201cMigra\u00e7\u00f5es, ref\u00fagio e comunidade crist\u00e3. Reflex\u00f5es pastorais para a forma\u00e7\u00e3o de agentes\u201d, realiza\u00e7\u00e3o em parceria com a Editora Paulus.<\/p><p>A <strong>S\u00e9rie Mem\u00f3rias<\/strong> p\u00fablica estudos e narrativas de abordagem hist\u00f3rica, sobretudo com foco na atua\u00e7\u00e3o das Irm\u00e3s Mission\u00e1rias Scalabrinianas.<\/p><p>A <strong>S\u00e9rie Ecumene <\/strong>visa responder a uma car\u00eancia de publica\u00e7\u00f5es de teologia da mobilidade humana voltada, prioritariamente, para lideran\u00e7as religiosas\/eclesiais que atuam nos \u00e2mbitos acad\u00eamico, institucional ou pastoral.<br \/>Desenvolvida em parceria com a CLAR \u2013 Confedera\u00e7\u00e3o Latino Americana de Religiosos, a S\u00e9rie Ecumene \u00e9 um projeto plurianual de produ\u00e7\u00e3o e publica\u00e7\u00e3o de estudos de teologia da mobilidade humana, com vistas a promover a reflex\u00e3o e a atua\u00e7\u00e3o no \u00e2mbito migrat\u00f3rio e do ref\u00fagio. O projeto editorial \u2013 S\u00e9rie Ecumene \u2013 produz, em portugu\u00eas e em espanhol, colet\u00e2neas tem\u00e1ticas relacionados com a mobilidade humana, que s\u00e3o disponibilizados, inclusive, em vers\u00e3o digital para\u00a0<strong><a href=\"https:\/\/csem.org.br\/csem-livros\/#serie-ecumene\" target=\"_blank\" rel=\"noopener\"><em><u>download<\/u><\/em><\/a><\/strong>\u00a0gratuito.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d436bb elementor-widget elementor-widget-heading\" data-id=\"8d436bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">REMHU<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8b19ca elementor-widget elementor-widget-text-editor\" data-id=\"c8b19ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">A principal publica\u00e7\u00e3o da Editora CSEM \u00e9 o peri\u00f3dico cient\u00edfico quadrimestral\u00a0<strong>REMHU \u2013 Revista Interdisciplinar da Mobilidade Humana<\/strong>. Seu objetivo \u00e9 oferecer ao mundo acad\u00eamico e aos articuladores sociais, pastorais e de pol\u00edticas migrat\u00f3rias an\u00e1lises interdisciplinares, amplas e aprofundadas de temas ligados \u00e0 mobilidade humana contempor\u00e2nea<\/p><p style=\"font-weight: 400;\">Para mais informa\u00e7\u00f5es, acesse o <strong><a href=\"https:\/\/csem.org.br\/csem-remhu\/\"><em>site da REMHU aqui.<\/em><\/a><\/strong><\/p><p><em>Para adquirir: <\/em><\/p><p>A Editora CSEM n\u00e3o disp\u00f5e de distribuidora pr\u00f3pria, por isso, para solicitar as publica\u00e7\u00f5es impressas pelo CSEM \u00e9 necess\u00e1rio entrar em contato atrav\u00e9s do site ou por email para o endere\u00e7o <a href=\"mailto:csem@csem.org.br\" target=\"_blank\" rel=\"noopener noreferrer\">csem@csem.org.br<\/a>. <strong>As vers\u00f5es digitais dos livros do CSEM est\u00e3o dispon\u00edveis para download gratuito no <\/strong><em><strong><a href=\"http:\/\/remhu.csem.org.br\/index.php\/remhu\/index\" target=\"_blank\" rel=\"noopener noreferrer\"><u>site<\/u><\/a>\u00a0<\/strong><\/em>e as <strong>vers\u00f5es digitais dos artigos da REMHU est\u00e3o dispon\u00edveis no site do SCIELO<\/strong>,\u00a0<u><em><strong><a href=\"http:\/\/www.scielo.br\/scielo.php?script=sci_serial&amp;pid=1980-8585&amp;lng=en&amp;nrm=iso\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/www.scielo.br\/scielo.php?script%3Dsci_serial%26pid%3D1980-8585%26lng%3Den%26nrm%3Diso&amp;source=gmail&amp;ust=1533141712111000&amp;usg=AFQjCNEWOA6oMvOg2OXhwB8m9XpQLCoxbg\">aqui<\/a><\/strong><\/em>.<\/u><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Menu r\u00e1pido EDITORA A Editora CSEM atua em dois eixos: a produ\u00e7\u00e3o e edi\u00e7\u00e3o da Revista Interdisciplinar da Mobilidade Humana \u2013 REMHU e a publica\u00e7\u00e3o de livros pr\u00f3prios ou em parceria com organiza\u00e7\u00f5es afins. Todas as atividades da Editora CSEM est\u00e3o relacionadas com o cumprimento da Miss\u00e3o do CSEM de fomentar, produzir e disseminar conhecimentos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-719","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Editora - CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/csem.org.br\/pt_br\/editora\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Editora - CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios\" \/>\n<meta property=\"og:description\" content=\"Menu r\u00e1pido EDITORA A Editora CSEM atua em dois eixos: a produ\u00e7\u00e3o e edi\u00e7\u00e3o da Revista Interdisciplinar da Mobilidade Humana \u2013 REMHU e a publica\u00e7\u00e3o de livros pr\u00f3prios ou em parceria com organiza\u00e7\u00f5es afins. Todas as atividades da Editora CSEM est\u00e3o relacionadas com o cumprimento da Miss\u00e3o do CSEM de fomentar, produzir e disseminar conhecimentos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/csem.org.br\/pt_br\/editora\/\" \/>\n<meta property=\"og:site_name\" content=\"CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-18T19:51:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/csem.org.br\\\/editora\\\/\",\"url\":\"https:\\\/\\\/csem.org.br\\\/editora\\\/\",\"name\":\"Editora - CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/csem.org.br\\\/en\\\/#website\"},\"datePublished\":\"2018-07-04T13:52:05+00:00\",\"dateModified\":\"2023-08-18T19:51:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/csem.org.br\\\/editora\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/csem.org.br\\\/editora\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/csem.org.br\\\/editora\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/csem.org.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Editora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/csem.org.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/csem.org.br\\\/en\\\/\",\"name\":\"CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/csem.org.br\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/csem.org.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/csem.org.br\\\/en\\\/#organization\",\"name\":\"CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios\",\"url\":\"https:\\\/\\\/csem.org.br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/csem.org.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/csem.org.br\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-2.png\",\"contentUrl\":\"https:\\\/\\\/csem.org.br\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-2.png\",\"width\":3620,\"height\":1537,\"caption\":\"CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios\"},\"image\":{\"@id\":\"https:\\\/\\\/csem.org.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/csem_scalabrinianas\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Editora - CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/csem.org.br\/pt_br\/editora\/","og_locale":"pt_BR","og_type":"article","og_title":"Editora - CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios","og_description":"Menu r\u00e1pido EDITORA A Editora CSEM atua em dois eixos: a produ\u00e7\u00e3o e edi\u00e7\u00e3o da Revista Interdisciplinar da Mobilidade Humana \u2013 REMHU e a publica\u00e7\u00e3o de livros pr\u00f3prios ou em parceria com organiza\u00e7\u00f5es afins. Todas as atividades da Editora CSEM est\u00e3o relacionadas com o cumprimento da Miss\u00e3o do CSEM de fomentar, produzir e disseminar conhecimentos [&hellip;]","og_url":"https:\/\/csem.org.br\/pt_br\/editora\/","og_site_name":"CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios","article_modified_time":"2023-08-18T19:51:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/csem.org.br\/editora\/","url":"https:\/\/csem.org.br\/editora\/","name":"Editora - CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios","isPartOf":{"@id":"https:\/\/csem.org.br\/en\/#website"},"datePublished":"2018-07-04T13:52:05+00:00","dateModified":"2023-08-18T19:51:31+00:00","breadcrumb":{"@id":"https:\/\/csem.org.br\/editora\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/csem.org.br\/editora\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/csem.org.br\/editora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/csem.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Editora"}]},{"@type":"WebSite","@id":"https:\/\/csem.org.br\/en\/#website","url":"https:\/\/csem.org.br\/en\/","name":"CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios","description":"","publisher":{"@id":"https:\/\/csem.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/csem.org.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/csem.org.br\/en\/#organization","name":"CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios","url":"https:\/\/csem.org.br\/en\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/csem.org.br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/csem.org.br\/wp-content\/uploads\/2023\/07\/LOGO-2.png","contentUrl":"https:\/\/csem.org.br\/wp-content\/uploads\/2023\/07\/LOGO-2.png","width":3620,"height":1537,"caption":"CSEM - Centro Scalabriniano de Estudos Migrat\u00f3rios"},"image":{"@id":"https:\/\/csem.org.br\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/csem_scalabrinianas\/"]}]}},"_links":{"self":[{"href":"https:\/\/csem.org.br\/pt_br\/wp-json\/wp\/v2\/pages\/719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/csem.org.br\/pt_br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/csem.org.br\/pt_br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/csem.org.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/csem.org.br\/pt_br\/wp-json\/wp\/v2\/comments?post=719"}],"version-history":[{"count":0,"href":"https:\/\/csem.org.br\/pt_br\/wp-json\/wp\/v2\/pages\/719\/revisions"}],"wp:attachment":[{"href":"https:\/\/csem.org.br\/pt_br\/wp-json\/wp\/v2\/media?parent=719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}